{"id":4503,"date":"2025-10-10T15:41:44","date_gmt":"2025-10-10T13:41:44","guid":{"rendered":"https:\/\/www.officejobz.be\/?post_type=jobs&#038;p=4503"},"modified":"2025-11-06T08:36:32","modified_gmt":"2025-11-06T07:36:32","slug":"responsable-logistique-eurofins","status":"publish","type":"jobs","link":"https:\/\/www.officejobz.be\/en\/jobs\/responsable-logistique-eurofins\/","title":{"rendered":"Responsable Logistique &#8211; Eurofins"},"content":{"rendered":"<p><strong>Eurofins<\/strong>, leader international dans le domaine de l\u2019analytique et des services de laboratoire, recherche un <strong data-start=\"237\" data-end=\"263\">Responsable Logistique<\/strong> pour son bureau de <strong data-start=\"283\" data-end=\"292\">Wavre<\/strong>. Ce poste vise \u00e0 optimiser la gestion des flux logistiques, garantir l\u2019efficacit\u00e9 des op\u00e9rations et soutenir la croissance de l\u2019entreprise.<\/p>\n<p>Lieu:<strong> Wavre<\/strong><\/p>\n<p>Nom de l\u2019entreprise: <a href=\"https:\/\/www.eurofins.be\/fr\/\"><strong>Eurofins<\/strong><\/a><\/p>\n<p>Type de contrat:<strong>\u00a0CDI \u00e1 plein-temps (on-site)<\/strong><\/p>\n<p><strong data-start=\"13\" data-end=\"25\">Eurofins<\/strong> est un groupe international sp\u00e9cialis\u00e9 dans les analyses et les services de laboratoire. L\u2019entreprise fournit des tests, des analyses et des services de soutien \u00e0 diff\u00e9rents secteurs, notamment l\u2019alimentation, l\u2019environnement, la pharmacie, la cosm\u00e9tique et les biotechnologies.<\/p>\n<h3><strong>\u00c1 propos du Job<\/strong><\/h3>\n<p>Nous recherchons\u00a0un(e)<strong> Responsable Logistique<\/strong>\u00a0minutieux(se) pour apporter un support \u00e0 la fabrication clinique de phase III du MAPS ; ce support comprend la gestion des donn\u00e9es de r\u00e9f\u00e9rence et des \u00e9chantillons GMP.<\/p>\n<ul>\n<li data-start=\"104\" data-end=\"225\">\n<p data-start=\"106\" data-end=\"225\">Enregistrer les ordres de fabrication dans SAP pour mati\u00e8res premi\u00e8res, interm\u00e9diaires et substances m\u00e9dicamenteuses.<\/p>\n<\/li>\n<li data-start=\"226\" data-end=\"307\">\n<p data-start=\"228\" data-end=\"307\">G\u00e9n\u00e9rer des rapports SAP r\u00e9guliers et garantir des donn\u00e9es fiables et \u00e0 jour.<\/p>\n<\/li>\n<li data-start=\"308\" data-end=\"387\">\n<p data-start=\"310\" data-end=\"387\">Suivre les emplacements de stockage et g\u00e9rer l\u2019inventaire des cong\u00e9lateurs.<\/p>\n<\/li>\n<li data-start=\"388\" data-end=\"506\">\n<p data-start=\"390\" data-end=\"506\">Coordonner la logistique des \u00e9chantillons : documentation, commandes, \u00e9tiquetage et transfert au contr\u00f4le qualit\u00e9.<\/p>\n<\/li>\n<li data-start=\"507\" data-end=\"608\">\n<p data-start=\"509\" data-end=\"608\">Participer aux r\u00e9unions d\u2019\u00e9quipe et contribuer \u00e0 la documentation et aux enqu\u00eates sur les \u00e9carts.<\/p>\n<\/li>\n<\/ul>\n<h3><strong>Votre Profil<\/strong><\/h3>\n<ul>\n<li data-start=\"104\" data-end=\"163\">\n<p data-start=\"106\" data-end=\"163\">Bachelier en gestion d&#8217;entreprise ou logistique requis.<\/p>\n<\/li>\n<li data-start=\"164\" data-end=\"219\">\n<p data-start=\"166\" data-end=\"219\">Minimum 2 ans d&#8217;exp\u00e9rience dans un poste similaire.<\/p>\n<\/li>\n<li data-start=\"220\" data-end=\"291\">\n<p data-start=\"222\" data-end=\"291\">Ma\u00eetrise des outils informatiques indispensable ; SAP est un atout.<\/p>\n<\/li>\n<li data-start=\"292\" data-end=\"350\">\n<p data-start=\"294\" data-end=\"350\">Connaissance de base des environnements GMP appr\u00e9ci\u00e9e.<\/p>\n<\/li>\n<li data-start=\"351\" data-end=\"408\">\n<p data-start=\"353\" data-end=\"408\">Compr\u00e9hension des principes des donn\u00e9es de r\u00e9f\u00e9rence.<\/p>\n<\/li>\n<li data-start=\"409\" data-end=\"472\">\n<p data-start=\"411\" data-end=\"472\">Souci du d\u00e9tail, fiabilit\u00e9, proactivit\u00e9 et esprit d&#8217;\u00e9quipe.<\/p>\n<\/li>\n<li data-start=\"473\" data-end=\"551\">\n<p data-start=\"475\" data-end=\"551\">Esprit dynamique, orient\u00e9 solutions et capable de prendre des initiatives.<\/p>\n<\/li>\n<li data-start=\"552\" data-end=\"636\">\n<p data-start=\"554\" data-end=\"636\">Excellentes comp\u00e9tences en communication \u00e9crite et orale en fran\u00e7ais et anglais.<\/p>\n<\/li>\n<\/ul>\n<h3><strong>Notre Offre<\/strong><\/h3>\n<ul>\n<li data-start=\"99\" data-end=\"170\">\n<p data-start=\"101\" data-end=\"170\">Emploi \u00e0 temps plein : 40 heures par semaine, du lundi au vendredi.<\/p>\n<\/li>\n<li data-start=\"171\" data-end=\"255\">\n<p data-start=\"173\" data-end=\"255\">Contrat \u00e0 dur\u00e9e ind\u00e9termin\u00e9e avec horaires flexibles (d\u00e9but entre 7h00 et 9h30).<\/p>\n<\/li>\n<li data-start=\"285\" data-end=\"331\">\n<p data-start=\"287\" data-end=\"331\">Ch\u00e8ques-repas : 8 euros par jour ouvrable.<\/p>\n<\/li>\n<li data-start=\"332\" data-end=\"375\">\n<p data-start=\"334\" data-end=\"375\">Eco-ch\u00e8ques : environ 250 euros par an.<\/p>\n<\/li>\n<li data-start=\"376\" data-end=\"418\">\n<p data-start=\"378\" data-end=\"418\">Assurance hospitalisation DKV incluse.<\/p>\n<\/li>\n<li data-start=\"419\" data-end=\"465\">\n<p data-start=\"421\" data-end=\"465\">12 jours de cong\u00e9 suppl\u00e9mentaires offerts.<\/p>\n<\/li>\n<li data-start=\"466\" data-end=\"541\">\n<p data-start=\"468\" data-end=\"541\">Solution pour compenser un nombre insuffisant de jours de cong\u00e9 l\u00e9gaux.<\/p>\n<\/li>\n<li data-start=\"542\" data-end=\"610\">\n<p data-start=\"544\" data-end=\"610\">Programme bien-\u00eatre en entreprise pour le mental et le physique.<\/p>\n<\/li>\n<li data-start=\"611\" data-end=\"680\">\n<p data-start=\"613\" data-end=\"680\">Acc\u00e8s \u00e0 Payflip pour g\u00e9rer et optimiser votre salaire facilement.<\/p>\n<\/li>\n<li data-start=\"681\" data-end=\"738\">\n<p data-start=\"683\" data-end=\"738\">Plateforme pour consulter des dermatologues en ligne.<\/p>\n<\/li>\n<li data-start=\"739\" data-end=\"822\">\n<p data-start=\"741\" data-end=\"822\">\u00c9quipe dynamique avec d\u00e9jeuners mensuels et activit\u00e9s de team building vari\u00e9es.<\/p>\n<\/li>\n<li data-start=\"823\" data-end=\"892\">\n<p data-start=\"825\" data-end=\"892\">Environnement de travail international, collaboratif et motivant.<\/p>\n<\/li>\n<li data-start=\"893\" data-end=\"994\">\n<p data-start=\"895\" data-end=\"994\">Opportunit\u00e9s de d\u00e9veloppement personnel via apprentissage pratique et formations suppl\u00e9mentaires.<\/p>\n<\/li>\n<\/ul>\n<p>Rejoignez <strong data-start=\"96\" data-end=\"116\">Eurofins \u00e0 Wavre<\/strong> et contribuez \u00e0 un environnement dynamique et innovant. Nous offrons des opportunit\u00e9s de d\u00e9veloppement professionnel, un poste en logistique stimulant, et la possibilit\u00e9 de travailler avec une \u00e9quipe internationale engag\u00e9e. Postulez d\u00e8s maintenant pour devenir notre prochain <strong data-start=\"405\" data-end=\"431\">Responsable Logistique<\/strong> et participez \u00e0 la r\u00e9ussite d\u2019un leader mondial dans les services d\u2019analyses et de laboratoire.<\/p>\n<p><strong>Officejobz.be\u00a0<\/strong>est l\u00e0 pour vous accompagner tout au long de votre processus de candidature et vous aider \u00e0 r\u00e9ussir. Cliquez\u00a0<strong><a href=\"https:\/\/www.officejobz.be\/fr\/job-seekers-guide\/\">ici<\/a>.<\/strong><\/p>\n<p><img decoding=\"async\" class=\"\" src=\"https:\/\/www.officejobz.be\/wp-content\/uploads\/2025\/03\/Untitled-300x219.webp\" width=\"74\" height=\"54\" \/><\/p>\n","protected":false},"featured_media":3530,"template":"","class_list":["post-4503","jobs","type-jobs","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"cubewp_post_meta":[],"taxonomies":[],"_links":{"self":[{"href":"https:\/\/www.officejobz.be\/en\/wp-json\/wp\/v2\/jobs\/4503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.officejobz.be\/en\/wp-json\/wp\/v2\/jobs"}],"about":[{"href":"https:\/\/www.officejobz.be\/en\/wp-json\/wp\/v2\/types\/jobs"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.officejobz.be\/en\/wp-json\/wp\/v2\/media\/3530"}],"wp:attachment":[{"href":"https:\/\/www.officejobz.be\/en\/wp-json\/wp\/v2\/media?parent=4503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}